{"id":2618,"date":"2022-06-08T15:25:45","date_gmt":"2022-06-08T13:25:45","guid":{"rendered":"https:\/\/arens-motors.com\/?p=2618"},"modified":"2022-06-17T13:46:54","modified_gmt":"2022-06-17T11:46:54","slug":"electric-hybrid-marine-in-amsterdam-kompakteste-range-extender-am-markt","status":"publish","type":"post","link":"https:\/\/arens-motors.com\/de\/2022\/06\/08\/electric-hybrid-marine-in-amsterdam-kompakteste-range-extender-am-markt\/","title":{"rendered":"ARENS MOTORS auf der ELECTRIC &#038; HYBRID MARINE EXPO in Amsterdam"},"content":{"rendered":"<h3>ARENS MOTORS pr\u00e4sentiert: Kompaktester Range Extender am Markt<\/h3>\n<p><strong>Vom 21. bis 23.06.2022 wird die ENGINEme GmbH unter der Marke \u201eARENS MOTORS\u201c die neueste Generation der ARENS RVI Marinemotoren pr\u00e4sentieren. Das Berliner Tech-Unternehmen zeigt mit dem ARENS RVI REX den kleinsten und leichtesten 10 kW Range Extender am Markt.<\/strong><\/p>\n<h3>DIE ZUKUNFT IST ELEKTRISCH<\/h3>\n<p>Damit die elektrische Freiheit auf dem Wasser nicht mit der Ladeinfrastruktur endet, braucht es neue L\u00f6sungsans\u00e4tze. Unter dem Einfluss der Energiewende nimmt das Interesse an batterieelektrischen Antrieben im Marinebereich zu. Die Nachfrage nach lokal emissionsfreier Fortbewegung in H\u00e4fen und Binnengew\u00e4ssern w\u00e4chst. Gleichzeitig ist Reichweitensicherheit auf See unverzichtbar. Doch wie lassen sich beide Forderungen wirtschaftlich und nachhaltig erf\u00fcllen?<\/p>\n<h3>HYBRIDANTRIEBE UND ALTERNATIVE KRAFTSTOFFE<\/h3>\n<p>Hybridantriebe kombinieren den batterieelektrischen Antrieb mit einem Verbrennungsmotor als Reichweitenverl\u00e4ngerer (\u201eRange Extender\u201c). Als Alternative zu herk\u00f6mmlichen Dieselaggregaten, werden wir in Amsterdam den kompaktesten und leichtesten Range Extender f\u00fcr marine Hybridantriebe am Markt pr\u00e4sentieren. Der ARENS RVI REX ist ein direkteinspritzender Zweizylinder-Boxermotor mit 10 kW Leistung und 35 kg Gewicht. Mit seiner Plug-and-Play Installation integriert er sich einfach und nahtlos in das Systemdesign. Die elektronische Steuerung verf\u00fcgt \u00fcber eine Schnittstelle f\u00fcr den Echtzeitdatenaustausch via CAN-BUS mit anderen Bordsteuerger\u00e4ten. Bei Bedarf ist eine Anpassung der Betriebseigenschaften des Motors an die individuelle Betriebsstrategie des Kunden m\u00f6glich. Ein besonderes Merkmal der RVI Technologie ist ihre Flexibilit\u00e4t in Hinblick auf Green Fuels und nachhaltiger Langzeitnutzung. Das Einspritzsystem erlaubt erlaubt die Verwendung von alternativen Kraftstoffen (Green Fuels), die je nach Art des synthetischen Kraftstoffs einen CO2-neutralen bzw. CO2-freien Motorenbetrieb erlauben. Zu diesen Zukunftskraftstoffen geh\u00f6ren im Bootsbereich u.a. Methanol (CH3OH) und das kohlenstofffreie Ammoniak (NH3).<\/p>\n<h3>ARENS RVI BOXER ALS RANGE-EXTENDER \u2013 POTENZIAL ZUR STANDARDL\u00d6SUNG<\/h3>\n<p>Der ARENS RVI REX basiert auf den RVI 379-2Z Boxermotoren der ENGINEme GmbH. Diese neuartigen Aggregate sind so konzipiert, dass sie als sogenannte \u201eTeilmotoren\u201c bzw. \u201eLongblocks\u201c ausgeliefert werden k\u00f6nnen, d.h. ohne marinetypische Baugruppen und Anbauteile wie Wendegetriebe oder Generator. Dies erm\u00f6glicht die Einbindung des Motors als Range-Extender oder Generatorantrieb f\u00fcr Yachten. Mit ihren 379 ccm erreichen die kleinen Kraftwerke ein Leistungs-Drehzahlverh\u00e4ltnis, dass sich mit leistungsgleichen Diesel-Innenbordern messen kann. Dabei wiegen die RVI Antriebe nur die H\u00e4lfte, sind deutlich kompakter und lassen sich einfacher verbauen. Da viertakttypische Teile wie Zylinderkopfventile, Nockenwelle, \u00d6l-Umlaufschmierung oder \u00d6l-Sumpf entfallen, ist der Betrieb nicht nur sehr wartungsarm, sondern auch unempfindlich gegen starke Lagever\u00e4nderungen z.B. durch Seegang oder Kr\u00e4ngung. Die Motoren sind ferner mit einem geschlossenen Kraftstoffsystem ausgestattet, das kein Austreten von Kraftstoff oder D\u00e4mpfen zul\u00e4sst.<\/p>\n\n<p>Hier k\u00f6nnen Sie sich f\u00fcr einen Besuch der ENGINEme GmbH unter der Marke \u201eARENS MOTORS\u201c <a href=\"https:\/\/www.electricandhybridmarineworldexpo.com\/en\/register.php\" target=\"_blank\" rel=\"noopener\"><em>auf der ELECTRIC &amp; HYBRID MARINE in Amsterdam registrieren<\/em><\/a>. Sie finden uns in Halle 8 am Stand 1410 ganz in der N\u00e4he der MEETINGS AND CONCESSIONS AREA.<\/p>\n\n<hr \/>\n<p><br \/>\n<style id='mailster-form-default' type='text\/css'>.mailster-embeded-form body{background:0;padding:0;margin:0}.mailster-embeded-form .mailster-form-body{padding:5px !important;margin:auto !important}.mailster-form-wrap{max-width:100%;max-height:95%;min-width:100px;-webkit-overflow-scrolling:touch}.mailster-form{margin-bottom:20px;position:relative}.mailster-form:before{content:'';position:absolute;display:block;height:100%;width:100%;z-index:1;background-repeat:no-repeat;background-position:center center;background-size:20px 20px;background-image:url('https:\/\/arens-motors.com\/wp-content\/plugins\/mailster\/assets\/css\/..\/img\/loading.gif');visibility:hidden;opacity:0;transition:opacity .15s ease-in-out}.mailster-form.loading:before{opacity:1;visibility:visible}@media only screen and (-webkit-min-device-pixel-ratio:2),only screen and (min-resolution:192dpi){.mailster-form:before{background-image:url('https:\/\/arens-motors.com\/wp-content\/plugins\/mailster\/assets\/css\/..\/img\/loading_2x.gif')}}.mailster-form:after,.mailster-form-fields:after{content:'.';visibility:hidden;display:block;height:0;clear:both}.mailster-form .mailster-form-fields{transition:all .15s ease-in-out}.mailster-form.completed .mailster-form-fields{height:0;min-height:0;opacity:0;overflow:hidden}.mailster-form,.mailster-form .input,.mailster-form .mailster-form-info{width:100%;box-sizing:border-box}.mailster-embeded-form .mailster-form{margin-bottom:3px}.mailster-form .mailster-wrapper{position:relative;margin-bottom:2px;transition:opacity .15s ease-in-out}.mailster-form.loading .mailster-wrapper{opacity:.2}.mailster-form textarea.input{resize:vertical;height:150px}.mailster-form li{list-style:none !important;margin-left:0;padding-left:0}span.mailster-required{font-size:120%;font-weight:700;color:#bf4d4d}.mailster-lists-wrapper ul{list-style:none;margin-left:0;padding-left:0}.mailster-lists-wrapper ul li{margin-left:0}.mailster-list-description{color:inherit;display:block;margin-left:25px;font-size:.8em}.mailster-form-info{height:0;border-radius:2px;padding:5px;margin-bottom:4px;color:#fff;padding:9px 16px;transition:all .2s;-webkit-transform:scale(0);-moz-transform:scale(0);-ms-transform:scale(0);transform:scale(0)}.mailster-form.loading .mailster-form-info{opacity:0}.mailster-form-info a{color:#fff}.mailster-form-info.success,.mailster-form-info.error{display:block;height:100%;-webkit-transform:scale(1);-moz-transform:scale(1);-ms-transform:scale(1);transform:scale(1)}.mailster-form .error input,.mailster-form .error select,.mailster-form .error textarea{outline:2px solid #bf4d4d;outline-offset:0}.mailster-form-info.error{background:#bf4d4d}.mailster-form-info.success{background-color:#6fbf4d;text-align:center}.mailster-form-info ul,.mailster-form .mailster-form-info p{margin:0;padding:0;max-width:initial}.mailster-form-info ul li{color:inherit;margin-left:0}.mailster-submit-wrapper{margin-top:6px}.mailster-form .submit-button{cursor:pointer}.mailster-form .submit-button:focus{outline:0}<\/style><form action=\"https:\/\/arens-motors.com\/de\/mailster\/subscribe\/\" method=\"post\" class=\"mailster-form mailster-form-submit mailster-ajax-form mailster-form-3\" novalidate><input name=\"_action\" type=\"hidden\" value=\"subscribe\">\n<input name=\"_timestamp\" type=\"hidden\" value=\"1784158132\">\n<input name=\"_referer\" type=\"hidden\" value=\"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/posts\/2618\">\n<input name=\"_nonce\" type=\"hidden\" value=\"4d5629bcd4\">\n<input name=\"formid\" type=\"hidden\" value=\"3\">\n<div class=\"mailster-form-fields\">\n<div class=\"mailster-wrapper mailster-email-wrapper\"><label for=\"mailster-email-3\">E-Mail <span class=\"mailster-required\">*<\/span><\/label><input id=\"mailster-email-3\" name=\"email\" type=\"email\" value=\"\" class=\"input mailster-email mailster-required\" aria-required=\"true\" aria-label=\"E-Mail\" spellcheck=\"false\"><\/div>\n<div style=\"position:absolute;top:-99999px;left:-99999px;z-index:-99;\"><input name=\"n_4b7fa42c95_email\" type=\"email\" tabindex=\"-1\" autocomplete=\"noton\" autofill=\"off\"><\/div>\n<div class=\"mailster-wrapper mailster-_gdpr-wrapper\"><label for=\"mailster-_gdpr-3\"><input type=\"hidden\" name=\"_gdpr\" value=\"0\"><input id=\"mailster-_gdpr-3\" name=\"_gdpr\" type=\"checkbox\" value=\"1\" class=\"mailster-_gdpr mailster-required\" aria-required=\"true\" aria-label=\"I agree to the privacy policy and terms.\"> I agree to the privacy policy and terms. (<a href=\"https:\/\/arens-motors.com\/de\/datenschutzerklaerung\/\" target=\"_top\">Link<\/a>)<\/label><\/div>\n<div class=\"mailster-wrapper mailster-submit-wrapper form-submit\"><input name=\"submit\" type=\"submit\" value=\"HIER ANMELDEN\" class=\"submit-button button\" aria-label=\"HIER ANMELDEN\"><\/div>\n<\/div>\n<\/form>\n\n","protected":false},"excerpt":{"rendered":"<p>ARENS MOTORS pr\u00e4sentiert: Kompaktester Range Extender am Markt Vom 21. bis 23.06.2022 wird die ENGINEme GmbH unter der Marke \u201eARENS MOTORS\u201c die neueste Generation der ARENS RVI Marinemotoren pr\u00e4sentieren. Das Berliner Tech-Unternehmen zeigt mit dem ARENS RVI REX den kleinsten und leichtesten 10 kW Range Extender am Markt. DIE ZUKUNFT IST ELEKTRISCH Damit die elektrische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16,37],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ARENS MOTORS auf der ELECTRIC &amp; HYBRID MARINE EXPO in Amsterdam - Arens Motors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARENS MOTORS auf der ELECTRIC &amp; HYBRID MARINE EXPO in Amsterdam - Arens Motors\" \/>\n<meta property=\"og:description\" content=\"ARENS MOTORS pr\u00e4sentiert: Kompaktester Range Extender am Markt Vom 21. bis 23.06.2022 wird die ENGINEme GmbH unter der Marke \u201eARENS MOTORS\u201c die neueste Generation der ARENS RVI Marinemotoren pr\u00e4sentieren. Das Berliner Tech-Unternehmen zeigt mit dem ARENS RVI REX den kleinsten und leichtesten 10 kW Range Extender am Markt. DIE ZUKUNFT IST ELEKTRISCH Damit die elektrische [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/\" \/>\n<meta property=\"og:site_name\" content=\"Arens Motors\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-08T13:25:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-17T11:46:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arens-motors.com\/wp-content\/uploads\/2022\/06\/ARENS_RVI_REX_15_V06_titel2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lars Arens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lars Arens\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arens-motors.com\/de\/2022\/06\/08\/electric-hybrid-marine-in-amsterdam-kompakteste-range-extender-am-markt\/\",\"url\":\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/\",\"name\":\"ARENS MOTORS auf der ELECTRIC & HYBRID MARINE EXPO in Amsterdam - Arens Motors\",\"isPartOf\":{\"@id\":\"https:\/\/arens-motors.com\/de\/#website\"},\"datePublished\":\"2022-06-08T13:25:45+00:00\",\"dateModified\":\"2022-06-17T11:46:54+00:00\",\"author\":{\"@id\":\"https:\/\/arens-motors.com\/de\/#\/schema\/person\/c5464e4998693fe0cc03081958258386\"},\"breadcrumb\":{\"@id\":\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/arens-motors.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ARENS MOTORS auf der ELECTRIC &#038; HYBRID MARINE EXPO in Amsterdam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arens-motors.com\/de\/#website\",\"url\":\"https:\/\/arens-motors.com\/de\/\",\"name\":\"Arens Motors\",\"description\":\"Arens Motors develops an extremely compact direct injection motor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arens-motors.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/arens-motors.com\/de\/#\/schema\/person\/c5464e4998693fe0cc03081958258386\",\"name\":\"Lars Arens\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/arens-motors.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0021984a9deb302eaaa676938a2fa1ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0021984a9deb302eaaa676938a2fa1ba?s=96&d=mm&r=g\",\"caption\":\"Lars Arens\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARENS MOTORS auf der ELECTRIC & HYBRID MARINE EXPO in Amsterdam - Arens Motors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/","og_locale":"de_DE","og_type":"article","og_title":"ARENS MOTORS auf der ELECTRIC & HYBRID MARINE EXPO in Amsterdam - Arens Motors","og_description":"ARENS MOTORS pr\u00e4sentiert: Kompaktester Range Extender am Markt Vom 21. bis 23.06.2022 wird die ENGINEme GmbH unter der Marke \u201eARENS MOTORS\u201c die neueste Generation der ARENS RVI Marinemotoren pr\u00e4sentieren. Das Berliner Tech-Unternehmen zeigt mit dem ARENS RVI REX den kleinsten und leichtesten 10 kW Range Extender am Markt. DIE ZUKUNFT IST ELEKTRISCH Damit die elektrische [&hellip;]","og_url":"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/","og_site_name":"Arens Motors","article_published_time":"2022-06-08T13:25:45+00:00","article_modified_time":"2022-06-17T11:46:54+00:00","og_image":[{"width":1400,"height":487,"url":"https:\/\/arens-motors.com\/wp-content\/uploads\/2022\/06\/ARENS_RVI_REX_15_V06_titel2.jpg","type":"image\/jpeg"}],"author":"Lars Arens","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lars Arens","Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arens-motors.com\/de\/2022\/06\/08\/electric-hybrid-marine-in-amsterdam-kompakteste-range-extender-am-markt\/","url":"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/","name":"ARENS MOTORS auf der ELECTRIC & HYBRID MARINE EXPO in Amsterdam - Arens Motors","isPartOf":{"@id":"https:\/\/arens-motors.com\/de\/#website"},"datePublished":"2022-06-08T13:25:45+00:00","dateModified":"2022-06-17T11:46:54+00:00","author":{"@id":"https:\/\/arens-motors.com\/de\/#\/schema\/person\/c5464e4998693fe0cc03081958258386"},"breadcrumb":{"@id":"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/engineme.com\/2021\/11\/08\/weltpremiere-metstrade-in-amsterdam-kompakteste-einbaumotoren-am-markt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/arens-motors.com\/de\/"},{"@type":"ListItem","position":2,"name":"ARENS MOTORS auf der ELECTRIC &#038; HYBRID MARINE EXPO in Amsterdam"}]},{"@type":"WebSite","@id":"https:\/\/arens-motors.com\/de\/#website","url":"https:\/\/arens-motors.com\/de\/","name":"Arens Motors","description":"Arens Motors develops an extremely compact direct injection motor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arens-motors.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/arens-motors.com\/de\/#\/schema\/person\/c5464e4998693fe0cc03081958258386","name":"Lars Arens","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/arens-motors.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0021984a9deb302eaaa676938a2fa1ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0021984a9deb302eaaa676938a2fa1ba?s=96&d=mm&r=g","caption":"Lars Arens"}}]}},"_links":{"self":[{"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/posts\/2618"}],"collection":[{"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/comments?post=2618"}],"version-history":[{"count":19,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/posts\/2618\/revisions"}],"predecessor-version":[{"id":2697,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/posts\/2618\/revisions\/2697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/media\/2685"}],"wp:attachment":[{"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/media?parent=2618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/categories?post=2618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arens-motors.com\/de\/wp-json\/wp\/v2\/tags?post=2618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}